{"id":110,"date":"2011-11-14T11:41:53","date_gmt":"2011-11-14T11:41:53","guid":{"rendered":"http:\/\/blogs.diariosur.es\/avuelapluma\/?p=110"},"modified":"2011-11-14T11:41:53","modified_gmt":"2011-11-14T11:41:53","slug":"ayuntamientos-asfixiados","status":"publish","type":"post","link":"https:\/\/blogs.diariosur.es\/avuelapluma\/2011\/11\/14\/ayuntamientos-asfixiados\/","title":{"rendered":"Ayuntamientos asfixiados"},"content":{"rendered":"<p>Es un secreto a voces que la mayor\u00eda de los ayuntamientos de la provincia \u00a0arrastran dificultades econ\u00f3micas sin cuento.\u00a0Es una noticia que vemos u o\u00edmos un d\u00eda s\u00ed y otro tambi\u00e9n. Muchos de ellos, est\u00e1n en pie de guerra contrala Administraci\u00f3n Auton\u00f3mica.Sus arcas, que antes recib\u00edan los aportes leg\u00edtimos de permisos de obras y urbanizaciones, ahora, por mor de la crisis financiera y econ\u00f3mica, se encuentran si no vac\u00edas y exang\u00fces\u00a0 del todo, s\u00ed a punto de estarlos o, por lo menos, en estado comatoso.<\/p>\n<p>\u00a0\u00a0\u00a0 Se cierran bibliotecas, van al paro profesoras de guarder\u00edas, instalaciones deportivas sin servicios, y\u00a0 en el peor de los casos calles y aceras sucias\u00a0 y montones de facturas sin pagar porque el presupuesto no llega para atenderlas puntualmente. A la lamentable situaci\u00f3n hay que a\u00f1adir la agudizaci\u00f3n del problema deficitario a partir de la inclusi\u00f3n en la discutida ley de recortes de Zapatero en\u00a0 2010, a saber, la prohibici\u00f3n a los ayuntamientos de \u00a0concertar cr\u00e9ditos a largo plazo.<\/p>\n<p>\u00a0\u00a0 Muchos se han rebelado \u00a0y han puesto el grito en el cielo ante la decisi\u00f3n del Ejecutivo de negarles el pan y la sal de los cr\u00e9ditos. \u00a0\u00a0Una situaci\u00f3n sobrevenida (que habr\u00eda que contemplar tras la mengua de licencias por obras y la obligaci\u00f3n de revertir en las arcas centrales los adelantos recibidos a cuenta), \u00a0que consideran con justicia insostenible. Las casas consistoriales, sin que est\u00e9n obligadas a ello, por ser tareas que competen al ente aut\u00f3nomo, han venido con harta frecuencia sac\u00e1ndole las casta\u00f1as del fuego a \u00e9ste. Y se entiende; el ayuntamiento de cada ciudad, de cada pueblo, con las excepciones de rigor (saboteados por alcaldes desaprensivos que lo consideran su cortijo y por ende tienden a exprimirles el mayor montante de ganancias en\u00a0 beneficio propio o de sus familias o amigos), que est\u00e1n en la mente de todos, se desviven por atender la demanda de la ciudadan\u00eda cuando es acuciante la necesidad de remodelar un centro educativo o de salud, pongo por caso.\u00a0\u00a0<\/p>\n<p>\u00a0 Con este panorama desolador los entes locales se ven obligados a recurrir a sus propios medios, que no son otros sino echar mano a los impuestos: subidas del IBI y del impuesto de circulaci\u00f3n, por ejemplo. Medidas coercitivas que no dejan de ser ingratas, las cuales al final se revuelven contra quienes las decretan, haci\u00e9ndoles pagar sus loables intenciones \u2013 al fin de cuentas lo que se aspira es a mantener una aceptable l\u00ednea de servicios &#8211;\u00a0 en las urnas. Las alcald\u00edas necesitan un respiro, siquiera sea porque en ellas como sentenci\u00f3 Arist\u00f3teles \u2013 se refer\u00eda a las \u201cpolis\u201d o peque\u00f1as comunidades &#8211; , \u201creside el gobierno por antonomasia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es un secreto a voces que la mayor\u00eda de los ayuntamientos de la provincia \u00a0arrastran dificultades econ\u00f3micas sin cuento.\u00a0Es una noticia que vemos u o\u00edmos un d\u00eda s\u00ed y otro tambi\u00e9n. Muchos de ellos, est\u00e1n en pie de guerra contrala Administraci\u00f3n Auton\u00f3mica.Sus arcas, que antes recib\u00edan los aportes leg\u00edtimos de permisos de obras y urbanizaciones, [&hellip;]<\/p>\n","protected":false},"author":27495,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-110","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/users\/27495"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}