{"id":36,"date":"2011-10-28T17:03:52","date_gmt":"2011-10-28T17:03:52","guid":{"rendered":"http:\/\/blogs.diariosur.es\/avuelapluma\/?p=36"},"modified":"2011-10-28T17:03:52","modified_gmt":"2011-10-28T17:03:52","slug":"otono-triste-en-la-serrania-de-ronda","status":"publish","type":"post","link":"https:\/\/blogs.diariosur.es\/avuelapluma\/2011\/10\/28\/otono-triste-en-la-serrania-de-ronda\/","title":{"rendered":"Oto\u00f1o triste en la Serran\u00eda de Ronda"},"content":{"rendered":"<p>El mar, su proximidad inquietante o lejana, dulcifica en la larga costa, sus tonos. Se retrasa, parece que llega, pero se vuelve y se rezaga. El oto\u00f1o, no es el mismo, cuando asoma cerca del mar, que cuando lo hace en la lejana monta\u00f1a. El pi\u00e9lago, profundo y calentado, apacigua su brusca entrada y parece decirle con voz atiplada: Espera un poco, camarada. Es menos visible, aunque las hojas de los \u00e1rboles tambi\u00e9n se caigan y se arremolinen en el suelo todav\u00eda sediento. Quiz\u00e1 su presencia m\u00e1s evidente sea el regreso de las gaviotas a la playa. Recuperan la arena, largamente usurpada.<\/p>\n<p>\u00a0\u00a0\u00a0 Llega sin avisar el oto\u00f1o a la monta\u00f1a. Un d\u00eda hace calor, fuego en las alturas y en las laderas hura\u00f1as, y al otro, el fr\u00edo extiende su albedr\u00edo con sa\u00f1a. Sin transici\u00f3n, casi sin pausa.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0De la \u00a0noche a la ma\u00f1ana. No se ve\u00eda ayer, y hoy es cosa clara. Al amanecer tenues gotas de roc\u00edo entorpecen del segador el corte de la guada\u00f1a. \u00bfC\u00f3mo tan pronto ha cambiado el color de la hojarasca? De verde brillante, en un soplo los tonos del caqui ( en el Jap\u00f3n de donde es oriundo y luego enla Serran\u00eda) planta santa, se pas\u00f3 a la p\u00e1tina amoratada. Se desnuda la higuera con parsimonia pero sin pausa. Le descolgaron los \u00faltimos higos que az\u00facar rezumaban. El almendro, los chopos de las riberas, las encinas ancianas, (no as\u00ed los olivos cenicientos y machadianos que ganaron en galanura) y los abedules perdieron su prestancia.<\/p>\n<p>\u00a0\u00a0\u00a0 Las colosales sierras que al cielo ara\u00f1an impiden que la luz se entretenga antes de despedirse hasta ma\u00f1ana. Es lo que en<\/p>\n<p>los pueblos de la costa pasa. En los de la monta\u00f1a anochece pronto: se esconden presurosas. Y las alturas incitan para que las sombras antes de tiempo las invadan con premura.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 Sopla el aire fr\u00edo y a su paso todo lo arrastra. Los que vienen de la costa les coge de sorpresa esta asta actitud rebelde y temprana. \u201cTodav\u00eda hay gente en la playa\u201d, dicen con destemplanza. \u201cNo es lo mismo en la sierra\u201d, le contestan los de Ronda, Montejaque, Alpandeire y Parauta. Aqu\u00ed es m\u00e1s triste y de m\u00e1s temprana pisada.<\/p>\n<p>\u00a0\u00a0\u00a0 No, no es lo mismo el oto\u00f1o en la costa que en la monta\u00f1a.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mar, su proximidad inquietante o lejana, dulcifica en la larga costa, sus tonos. Se retrasa, parece que llega, pero se vuelve y se rezaga. El oto\u00f1o, no es el mismo, cuando asoma cerca del mar, que cuando lo hace en la lejana monta\u00f1a. El pi\u00e9lago, profundo y calentado, apacigua su brusca entrada y parece [&hellip;]<\/p>\n","protected":false},"author":27495,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-36","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/users\/27495"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}