{"id":96,"date":"2011-11-06T18:47:19","date_gmt":"2011-11-06T18:47:19","guid":{"rendered":"http:\/\/blogs.diariosur.es\/avuelapluma\/?p=96"},"modified":"2011-11-06T18:47:19","modified_gmt":"2011-11-06T18:47:19","slug":"campana-sin-incognitas","status":"publish","type":"post","link":"https:\/\/blogs.diariosur.es\/avuelapluma\/2011\/11\/06\/campana-sin-incognitas\/","title":{"rendered":"Campa\u00f1a sin inc\u00f3gnitas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"font-family: Times New Roman;\">Todos los datos apuntan a que nos encontramos ante unas elecciones cuyo desenlace final es de f\u00e1cil previsi\u00f3n. En nuestra joven democracia no hab\u00eda ocurrido antes. En la carrera que ahora acaba de abrirse (recurriendo aun t\u00e9rmino h\u00edpico)\u00a0se apuesta fuerte por el caballo ganador, el cual acapara todos los vaticinios que le auguran una gran victoria. La encuesta del CIS no deja lugar a dudas. El Partido Popular enfila hacia una victoria de las que hacen historia. La muestra ha sido amplia \u2013 17.000 entrevistas- lo que despeja muchas dudas del resultado final. Pero son las urnas las que tienen la \u00faltima palabra.<\/span><\/p>\n<p><span style=\"font-family: Times New Roman;\">\u00a0\u00a0Aunque \u00a0resulte arriesgado fiarse de las encuestas pol\u00edticas el resultado ha sido tan contundente que nos hace pensar que con \u00e9l en la mano se despejan la mayor\u00eda de las inc\u00f3gnitas, sobre todo si se tiene en cuenta el anunciado sorpasso en Andaluc\u00eda. En la tierra de Mar\u00eda Sant\u00edsima, la encuesta otorga a los populares la victoria en siete de las ocho provincias. Tal vez se salga de la cazoleta Sevilla, donde se ha echado mano de la vieja guardia socialista para contrarrestar el empuje avasallador del contrincante. Gonz\u00e1lez y Guerra recurrieron a la estrategia de magnificar los resultados obtenidos contra ETA, \u00bfpero no se acord\u00f3 que el terrorismo no ser\u00eda enarbolado en la campa\u00f1a? \u00a0<\/span><\/p>\n<p><span style=\"font-family: Times New Roman;\">Por todo ello, estamos ante una campa\u00f1a aburrida con un final cantado de antemano. Meditemos sobre los que unos y otros prometen, pero sin dejar sde lado a sentencia de Otto von Bismark: &#8221; Nunca se miente tanto como antes de las elecciones, durante una guerra y despu\u00e9s de una cacer\u00eda&#8221;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Todos los datos apuntan a que nos encontramos ante unas elecciones cuyo desenlace final es de f\u00e1cil previsi\u00f3n. En nuestra joven democracia no hab\u00eda ocurrido antes. En la carrera que ahora acaba de abrirse (recurriendo aun t\u00e9rmino h\u00edpico)\u00a0se apuesta fuerte por el caballo ganador, el cual acapara todos los vaticinios que le auguran una [&hellip;]<\/p>\n","protected":false},"author":27495,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-96","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/users\/27495"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/posts\/96\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/media?parent=96"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/categories?post=96"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/avuelapluma\/wp-json\/wp\/v2\/tags?post=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}