{"id":31,"date":"2007-02-09T13:05:25","date_gmt":"2007-02-09T13:05:25","guid":{"rendered":"http:\/\/blogs.diariosur.es\/blogmalayo\/?p=31"},"modified":"2007-02-09T13:05:25","modified_gmt":"2007-02-09T13:05:25","slug":"un-nuevo-personaje-principal","status":"publish","type":"post","link":"https:\/\/blogs.diariosur.es\/blogmalayo\/2007\/02\/09\/un-nuevo-personaje-principal\/","title":{"rendered":"UN NUEVO PERSONAJE PRINCIPAL"},"content":{"rendered":"<p>El &#8216;caso Malaya&#8217; tiene un nuevo encarcelado. El abogado Juan Hoffmann ya duerme en Alhaur\u00edn de la Torre despu\u00e9s de haber pasado una noche en la comisar\u00eda provincial y otra en el arresto municipal de Marbella.<br \/>\nLlaman la atenci\u00f3n algunos aspectos relacionados con este nuevo imputado. Cuando cab\u00eda suponer que ya no habr\u00eda m\u00e1s detenidos o que a lo sumo se producir\u00edan algunos coletazos, como la detenci\u00f3n del &#8216;joyero de Roca&#8217;, el caso ha sumado a un nuevo personaje que seguramente distar\u00e1 de ser un secundario. El registro del despacho donde aparentemente ya no trabajaba fue el m\u00e1s largo que recuerda la operaci\u00f3n: m\u00e1s de 16 horas, y el interrogatorio al que lo someti\u00f3 el juez tampoco se qued\u00f3 atr\u00e1s: cinco horas y media. Tambi\u00e9n la medida adoptada, prisi\u00f3n incondicional cuando apenas quedaban tres encarcelados, es tambi\u00e9n un claro indicio de la importancia que el juez atribuye a este abogado en la trama de blanqueo.<br \/>\nPero adem\u00e1s no se trata de un personaje nuevo para quienes siguen el sumario. Su nombre ha aparecido repetidamente en una de las declaraciones de Juan Antonio Roca, y  no porque el presunto cerebro de la trama lo citara, sino porque el juez le pregunt\u00f3 por \u00e9l. Desde esa comparecencia de Roca han pasado ya seis meses.<br \/>\nEn el auto de prisi\u00f3n se justifica la medida en que la investigaci\u00f3n todav\u00eda contin\u00faa. Sin embargo, debe suponerse que ya no existe riesgo de destrucci\u00f3n de pruebas. Ha habido tiempo m\u00e1s que suficiente para ello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El &#8216;caso Malaya&#8217; tiene un nuevo encarcelado. El abogado Juan Hoffmann ya duerme en Alhaur\u00edn de la Torre despu\u00e9s de haber pasado una noche en la comisar\u00eda provincial y otra en el arresto municipal de Marbella. Llaman la atenci\u00f3n algunos aspectos relacionados con este nuevo imputado. Cuando cab\u00eda suponer que ya no habr\u00eda m\u00e1s detenidos [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/posts\/31"}],"collection":[{"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariosur.es\/blogmalayo\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}